{"id":7904,"date":"2025-06-01T10:00:00","date_gmt":"2025-06-01T13:00:00","guid":{"rendered":"https:\/\/sobelconsult.com\/unterstuetzung-im-qualitaetsmanagement-brasilien\/"},"modified":"2026-04-11T16:33:05","modified_gmt":"2026-04-11T19:33:05","slug":"quality-management-system-brazil","status":"publish","type":"page","link":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/","title":{"rendered":"Unterst\u00fctzung im Qualit\u00e4tsmanagement - Brasilien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7904\" class=\"elementor elementor-7904 elementor-1675\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6311308 e-flex e-con-boxed e-con e-parent\" data-id=\"6311308\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d00542 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5d00542\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4tsmanagementsystem in Brasilien<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bb0e74 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9bb0e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Aligning your quality management system with both Brazilian and international standards can be complex and time-consuming. We help medical device manufacturers meet RDC 665\/2022 and ISO 13485 requirements\u2014making compliance simpler and faster.\"}]\" data-inline-monday=\"true\">Die Anpassung Ihres Qualit\u00e4tsmanagementsystems an brasilianische und internationale Standards kann komplex und zeitaufw\u00e4ndig sein. Wir helfen Herstellern von Medizinprodukten, die Anforderungen der RDC 665\/2022 und der ISO 13485 zu erf\u00fcllen - das macht die Einhaltung einfacher und schneller. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f30d1d elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"2f30d1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0MywidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Holen Sie sich Expertenunterst\u00fctzung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-749d8ce e-flex e-con-boxed e-con e-parent\" data-id=\"749d8ce\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ee929b6 e-con-full e-flex e-con e-child\" data-id=\"ee929b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-233d017 e-con-full e-transform e-flex e-con e-child\" data-id=\"233d017\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:96,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-109,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-051dd39 elementor-widget elementor-widget-heading\" data-id=\"051dd39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">F\u00fcr wen?<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea79f39 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ea79f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a140549 elementor-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a140549\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hersteller, die in den brasilianischen Markt eintreten oder die Einhaltung der Vorschriften aufrechterhalten m\u00f6chten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unternehmen, die die GMP-Zertifizierung von Anvisa erhalten oder erneuern m\u00f6chten.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Organisationen, die bereits nach ISO 13485 zertifiziert sind und sich an die RDC 665\/2022 anpassen m\u00fcssen.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Qualit\u00e4ts- und Regulierungsteams, die externes Fachwissen zur Validierung oder Optimierung ihrer Systeme suchen.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec72154 e-con-full e-flex e-con e-child\" data-id=\"ec72154\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce4a6d0 elementor-widget elementor-widget-image\" data-id=\"ce4a6d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"755\" height=\"1024\" src=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/image-medcialdevices-services-755x1024.png\" class=\"attachment-large size-large wp-image-18565\" alt=\"A portable vital signs monitor sits on a table. Office supplies are also on the table. It looks like a doctor&#039;s office.\" srcset=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/image-medcialdevices-services-755x1024.png 755w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/image-medcialdevices-services-221x300.png 221w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/image-medcialdevices-services-768x1041.png 768w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/image-medcialdevices-services.png 1011w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88f1be7 e-flex e-con-boxed e-con e-parent\" data-id=\"88f1be7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c5729f elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0c5729f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Whether you\u2019re starting from scratch or adapting an existing system, our support makes compliance clearer, leaner, and more strategic.\"}]\" data-inline-monday=\"true\">Ganz gleich, ob Sie bei Null anfangen oder ein bestehendes System anpassen, unsere Unterst\u00fctzung macht die Einhaltung von Vorschriften klarer, schlanker und strategischer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b37a626 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"b37a626\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0MywidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Holen Sie sich Unterst\u00fctzung!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07ee378 e-flex e-con-boxed e-con e-parent\" data-id=\"07ee378\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac96dfb elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"ac96dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1259\" height=\"275\" src=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/rectangle-md-blue.png\" class=\"attachment-full size-full wp-image-18571\" alt=\"Vector rectangle blue\" srcset=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/rectangle-md-blue.png 1259w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/rectangle-md-blue-300x66.png 300w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/rectangle-md-blue-1024x224.png 1024w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/10\/rectangle-md-blue-768x168.png 768w\" sizes=\"(max-width: 1259px) 100vw, 1259px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-547c2bf elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"547c2bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum brauchen Sie diesen Service?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47c3e97 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"47c3e97\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-69b392f e-con-full e-flex e-con e-child\" data-id=\"69b392f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22470c1 elementor-widget elementor-widget-text-editor\" data-id=\"22470c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Implementing a compliant Quality Management System is mandatory for Anvisa GMP certification under RDC 665\/2022.\"}]\" data-inline-monday=\"true\">Die Einf\u00fchrung eines konformen Qualit\u00e4tsmanagementsystems ist f\u00fcr die GMP-Zertifizierung durch Anvisa gem\u00e4\u00df RDC 665\/2022 obligatorisch.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-577ca43 e-con-full e-flex e-con e-child\" data-id=\"577ca43\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84e493e elementor-widget elementor-widget-text-editor\" data-id=\"84e493e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Aligning your QMS with ISO 13485 and Brazilian requirements ensures consistency, traceability, and readiness for inspections.\"}]\" data-inline-monday=\"true\">Die Anpassung Ihres QMS an die ISO 13485 und die brasilianischen Anforderungen gew\u00e4hrleistet Konsistenz, R\u00fcckverfolgbarkeit und Bereitschaft f\u00fcr Inspektionen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37c19fc e-con-full e-flex e-con e-child\" data-id=\"37c19fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-458ccbe elementor-widget elementor-widget-text-editor\" data-id=\"458ccbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Early identification of gaps reduces the risk of non-conformities, certification delays, and costly rework.\"}]\" data-inline-monday=\"true\">Die fr\u00fchzeitige Identifizierung von L\u00fccken verringert das Risiko von Nichtkonformit\u00e4ten, Verz\u00f6gerungen bei der Zertifizierung und kostspieliger Nacharbeit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6104d5e e-flex e-con-boxed e-con e-parent\" data-id=\"6104d5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad02c83 e-con-full e-flex e-con e-child\" data-id=\"ad02c83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41b24d1 elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"41b24d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aufbau eines gesetzeskonformen und effizienten Qualit\u00e4tsmanagementsystems in Brasilien<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9042bcf e-con-full e-flex e-con e-child\" data-id=\"9042bcf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e375786 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e375786\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere Experten begleiten Sie durch alle Phasen - von der Dokumentenanalyse und der Identifizierung von L\u00fccken bis hin zur Vorbereitung auf das Audit - damit Ihr Unternehmen f\u00fcr die GMP-Zertifizierung ger\u00fcstet ist und sich sicher f\u00fchlen kann!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6345a0e e-flex e-con-boxed e-con e-parent\" data-id=\"6345a0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b26a77 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2b26a77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technisches Fachwissen, Einblicke in die Vorschriften und individuelle Beratung.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0640829 elementor-widget elementor-widget-ucaddon_horizontal_timeline\" data-id=\"0640829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_horizontal_timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Horizontal Timeline -->\n\t\t<link id='font-awesome-css' href='https:\/\/sobelconsult.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/sobelconsult.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/sobelconsult.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Horizontal Timeline *\/\n\n#uc_horizontal_timeline_elementor_0640829 *{\n  box-sizing:border-box;\n}\n\n#uc_horizontal_timeline_elementor_0640829{\n  position:relative;\n  min-height:1px;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-carousel-content{\n    display: flex;\n    flex-flow: column nowrap;\n    flex:1;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-carousel-item{\n  overflow:hidden;\n  position:relative;\n  display:flex;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-btn-holder{\n  margin-top:auto;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-btn{\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n} \n\n#uc_horizontal_timeline_elementor_0640829 .item-horizontal-timeline .ue-item-title{\n  font-size:21px;\n  text-decoration:none;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .carousel-nav{\n  position:relative;\n  z-index:10;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .carousel-nav .carousel-prev{\n    position:absolute;\n      display:inline-block;    \n}\n\n#uc_horizontal_timeline_elementor_0640829 .carousel-nav .carousel-next{\n  position:absolute;\n  display:inline-block;    \n}\n\n#uc_horizontal_timeline_elementor_0640829  .carousel-nav button svg, \n#uc_horizontal_timeline_elementor_0640829  .carousel-nav button i{\n  position: absolute;\n     top: 50%;\n  left: 50%;\n  transform: translate(-50%, -50%);\n}\n\n#uc_horizontal_timeline_elementor_0640829 .owl-dots {\n  overflow:hidden;\n  display:true !important;  \n}\n\n#uc_horizontal_timeline_elementor_0640829 .owl-dot {\n  border-radius:50%;\n  display:inline-block;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-bullet-holder{\n  display:flex;\n  align-items:center;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-bullet-line{\n  flex-grow:1;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-bullet-line-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-bullet{\n  position:relative;\n  transition: all .3s ease;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-bullet i, #uc_horizontal_timeline_elementor_0640829 .ue-item-bullet svg{\n  position: absolute;\n  top: 50%;\n  left: 50%;\n  transform: translate(-50%, -50%); \n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-label a{\n  font-size:12px;\n  line-height:1.5em;\n  text-decoration:none;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-image{\n  overflow:hidden;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-image a{\n  display:block;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-image img{\n  object-fit: cover;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-vertical-line-holder{\n  display:flex;\n  justify-content:center; \n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-pointer-holder{\n  display:flex;\n  justify-content:center; \n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-carousel-item:hover .ue-item-image img{\n  transform:scale(1.1,1.1);\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-item-label{\n display:inline-block;\n}\n\n#uc_horizontal_timeline_elementor_0640829 .ue-carousel-item-holder{\n  display: flex;\n  flex-direction: column;\n  align-items: stretch;\n  height:100%;\n}\n\n<\/style>\n\n<div class=\"ue-horizontal-timeline\" id=\"uc_horizontal_timeline_elementor_0640829\">\n     <div class=\"carousel-nav\">\n            <button class=\"carousel-prev\" aria-label=\"Previous\">\n                <i class=' ti-arrow-circle-left'><\/i>\n            <\/button>\n            <button class=\"carousel-next\" aria-label=\"Next\">\n                <i class=' ti-arrow-circle-right'><\/i>\n            <\/button>\n        <\/div>\n    <div class=\"owl-carousel owl-theme uc-items-wrapper item-horizontal-timeline  \" id=\"uc_horizontal_timeline_elementor_0640829\" data-custom-sethtml=\"true\"  >\n     \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-ed34ef6\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >W\u00e4hlen Sie Ihre Art der Unterst\u00fctzung<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">W\u00e4hlen Sie den Service, der den Bed\u00fcrfnissen Ihres Unternehmens am besten entspricht - interne Audits oder Gap-Analysen auf der Grundlage von RDC 665\/2022 oder ISO 13485.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-a6513ad\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >Wir f\u00fchren die Bewertung durch<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">Unsere Experten f\u00fchren das Audit oder die L\u00fcckenbewertung per Fernzugriff oder vor Ort durch und identifizieren St\u00e4rken, L\u00fccken und Nichtkonformit\u00e4ten.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-c73e9b6\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >Erhalten Sie Ihren Fahrplan f\u00fcr die Einhaltung der Vorschriften<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">Sie erhalten einen klaren, umsetzbaren Bericht, der aufzeigt, was zu tun ist, um die vollst\u00e4ndige Einhaltung der brasilianischen und internationalen Standards im QMS zu erreichen.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Horizontal Timeline -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6706289 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6706289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0MywidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Beginnen Sie jetzt!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0521520 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"0521520\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86ab1e1 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"86ab1e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Welcher Service unterst\u00fctzt Ihr Qualit\u00e4tsmanagementsystem am besten?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e59013 elementor-widget elementor-widget-text-editor\" data-id=\"1e59013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Depending on your company\u2019s goals and regulatory stage, you can request an internal audit, a gap analysis against RDC 665\/2022, or a gap analysis against ISO 13485.\"}]\" data-inline-monday=\"true\">Je nach den Zielen Ihres Unternehmens und dem Stand der Regulierung k\u00f6nnen Sie ein internes Audit, eine L\u00fcckenanalyse gem\u00e4\u00df RDC 665\/2022 oder eine L\u00fcckenanalyse gem\u00e4\u00df ISO 13485 anfordern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22c31d7 e-con-full e-flex e-con e-child\" data-id=\"22c31d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d727e1d e-con-full e-flex e-con e-child\" data-id=\"d727e1d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b13bce8 elementor-widget elementor-widget-heading\" data-id=\"b13bce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Interne Revision<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b86791b elementor-widget elementor-widget-text-editor\" data-id=\"b86791b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Best if you need an independent, structured assessment to verify compliance, evaluate documentation, and identify non-conformities in your Quality Management System.\"}]\" data-inline-monday=\"true\">Am besten, wenn Sie eine unabh\u00e4ngige, strukturierte Bewertung ben\u00f6tigen, um die Einhaltung der Vorschriften zu \u00fcberpr\u00fcfen, die Dokumentation zu bewerten und Nichtkonformit\u00e4ten in Ihrem Qualit\u00e4tsmanagementsystem zu identifizieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af2fc20 e-con-full e-flex e-con e-child\" data-id=\"af2fc20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f1de02 elementor-widget elementor-widget-heading\" data-id=\"0f1de02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u00fcckenanalyse (RDC 665\/2022)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe7120b elementor-widget elementor-widget-text-editor\" data-id=\"fe7120b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Ideal for companies preparing for Anvisa GMP certification. This analysis checks your QMS against Brazilian requirements and highlights what needs to be improved before an inspection.\"}]\" data-inline-monday=\"true\">Ideal f\u00fcr Unternehmen, die sich auf die GMP-Zertifizierung durch Anvisa vorbereiten. Diese Analyse \u00fcberpr\u00fcft Ihr QMS anhand der brasilianischen Anforderungen und zeigt auf, was vor einer Inspektion verbessert werden muss. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f13481f e-con-full e-flex e-con e-child\" data-id=\"f13481f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c675c51 elementor-widget elementor-widget-heading\" data-id=\"c675c51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u00fcckenanalyse (ISO 13485:2016)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eda9d3b elementor-widget elementor-widget-text-editor\" data-id=\"eda9d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Recommended if you want to align your QMS with international standards. It helps ensure your processes, documentation, and quality manual meet ISO 13485 expectations.\"}]\" data-inline-monday=\"true\">Empfohlen, wenn Sie Ihr QMS an die internationalen Standards anpassen m\u00f6chten. Es hilft Ihnen sicherzustellen, dass Ihre Prozesse, Ihre Dokumentation und Ihr Qualit\u00e4tshandbuch den Erwartungen der ISO 13485 entsprechen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fd5bb elementor-widget elementor-widget-text-editor\" data-id=\"f7fd5bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"From targeted assessments to complete system reviews, Sobel provides the structure your company needs to achieve a compliant and effective Quality Management System in Brazil.\"}]\" data-inline-monday=\"true\">Von gezielten Bewertungen bis hin zu vollst\u00e4ndigen System\u00fcberpr\u00fcfungen bietet Sobel die Struktur, die Ihr Unternehmen ben\u00f6tigt, um ein konformes und effektives Qualit\u00e4tsmanagementsystem in Brasilien zu erreichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d164ba e-flex e-con-boxed e-con e-parent\" data-id=\"0d164ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d33c42 e-con-full e-flex e-con e-child\" data-id=\"2d33c42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3265a82 elementor-widget__width-inherit elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"3265a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15f0441 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"15f0441\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verwandte Dienstleistungen <br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-527198e elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"527198e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"A strong Quality Management System in Brazil is essential to access and thrive in the local medical device market. You can also count on regulatory support to complement your QMS strategy:\"}]\" data-inline-monday=\"true\">Ein starkes Qualit\u00e4tsmanagementsystem ist in Brasilien unabdingbar, um auf dem lokalen Markt f\u00fcr Medizinprodukte Fu\u00df zu fassen und erfolgreich zu sein. Sie k\u00f6nnen auch auf regulatorische Unterst\u00fctzung z\u00e4hlen, um Ihre QMS-Strategie zu erg\u00e4nzen: <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5404462 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5404462\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fc2d73f e-con-full e-flex e-con e-child\" data-id=\"fc2d73f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e66be69 elementor-widget elementor-widget-heading\" data-id=\"e66be69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Biologische Bewertung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af21116 elementor-widget elementor-widget-text-editor\" data-id=\"af21116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Complete Biological Evaluation for devices, aligned with ISO 10993 for safety &amp; compliance.\"}]\" data-inline-monday=\"true\">Vollst\u00e4ndige biologische Bewertung f\u00fcr Ger\u00e4te, abgestimmt auf ISO 10993 f\u00fcr Sicherheit und Konformit\u00e4t.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0bbe11 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c0bbe11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/biological-evaluation-brazil\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr sehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-890f61c e-con-full e-flex e-con e-child\" data-id=\"890f61c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c37558 elementor-widget elementor-widget-heading\" data-id=\"8c37558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Klinische Bewertung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f41fb5e elementor-widget elementor-widget-text-editor\" data-id=\"f41fb5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d42130 elementor-widget elementor-widget-text-editor\" data-id=\"7d42130\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-element elementor-element-7d42130 elementor-widget elementor-widget-text-editor\" data-id=\"7d42130\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Clinical Evaluation aligned with Guidance n\u00ba 31\/2020 \u2013 version 2, ensuring device safety.\"}]\" data-inline-monday=\"true\">Klinische Bewertung im Einklang mit der Leitlinie 31\/2020 - Version 2, die die Sicherheit des Produkts gew\u00e4hrleistet.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-596c884 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"596c884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/clinical-evaluation-brazil\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr sehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7006ed e-con-full e-flex e-con e-child\" data-id=\"c7006ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-682291e elementor-widget elementor-widget-heading\" data-id=\"682291e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inhaber der brasilianischen Registrierung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ffc6be elementor-widget elementor-widget-text-editor\" data-id=\"5ffc6be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Navigate market access in Brazil with Sobel as your device registration holder.\"}]\" data-inline-monday=\"true\">Navigieren Sie zum Marktzugang in Brasilien mit Sobel als Inhaber der Ger\u00e4teregistrierung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-512e6ac elementor-align-center elementor-widget elementor-widget-button\" data-id=\"512e6ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/brazilian-registration-holder\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr sehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fb1cc5 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"7fb1cc5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c6c0fd e-con-full e-flex e-con e-child\" data-id=\"4c6c0fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e66d4da e-con-full e-flex e-con e-child\" data-id=\"e66d4da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4233e9d elementor-widget-laptop__width-initial elementor-widget elementor-widget-heading\" data-id=\"4233e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erreichen Sie die vollst\u00e4ndige Einhaltung des QMS mit Unterst\u00fctzung von Experten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20fc730 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"20fc730\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"A compliant Quality Management System in Brazil is the foundation of every successful medical device operation. At Sobel, we go beyond identifying gaps\u2014we help you understand and apply the right standards with clarity and confidence.\"}]\" data-inline-monday=\"true\">Ein konformes Qualit\u00e4tsmanagementsystem in Brasilien ist die Grundlage f\u00fcr jede erfolgreiche T\u00e4tigkeit im Bereich Medizinprodukte. Wir von Sobel gehen \u00fcber die Identifizierung von L\u00fccken hinaus - wir helfen Ihnen, die richtigen Standards zu verstehen und mit Klarheit und Vertrauen anzuwenden. <\/p>\n<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Our experts combine local regulatory knowledge and international experience to support your company in every phase!\"}]\" data-inline-monday=\"true\"><strong>Unsere Experten kombinieren lokales regulatorisches Wissen und internationale Erfahrung, um Ihr Unternehmen in jeder Phase zu unterst\u00fctzen!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc173b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bfc173b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0MywidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Beginnen Sie jetzt!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af00dd4 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"af00dd4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cec3375 elementor-widget__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"cec3375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2161\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2161\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Haben Sie noch Fragen? Schauen Sie in unsere FAQ <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2161\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2161\"><p><b>1. Was ist ein Qualit\u00e4tsmanagementsystem (QMS) f\u00fcr Medizinprodukte in Brasilien?<\/b><\/p>\n<p>Ein Qualit\u00e4tsmanagementsystem (QMS) ist ein strukturierter Satz von Richtlinien, Prozessen und Verfahren, die sicherstellen, dass Medizinprodukte konsistent gem\u00e4\u00df regulatorischen und Qualit\u00e4tsstandards wie ISO 13485 und RDC 665\/2022 entwickelt, hergestellt und kontrolliert werden.<\/p>\n<p><b>2. Ist ein QMS f\u00fcr den Verkauf von Medizinprodukten in Brasilien obligatorisch?<\/b><\/p>\n<p>Ja. F\u00fcr Produkte der Klassen III und IV verlangt Anvisa von den Unternehmen, dass sie ein konformes QMS einf\u00fchren und eine GMP-Zertifizierung gem\u00e4\u00df RDC 665\/2022 erhalten, bevor die Registrierung genehmigt wird. Auch Produkte der Klassen I und II profitieren von strukturierten Qualit\u00e4tsmanagementpraktiken, um R\u00fcckverfolgbarkeit und Sicherheit zu gew\u00e4hrleisten.  <\/p>\n<p><b>3. Was ist der Unterschied zwischen ISO 13485 und RDC 665\/2022?<\/b><\/p>\n<p>ISO 13485 ist ein internationaler Standard f\u00fcr das Qualit\u00e4tsmanagement von Medizinprodukten, w\u00e4hrend RDC 665\/2022 die brasilienspezifischen Anforderungen an die Gute Herstellungspraxis (GMP) definiert. Ein konformes QMS in Brasilien muss mit beiden Normen \u00fcbereinstimmen, um globale Konsistenz und lokale beh\u00f6rdliche Genehmigung zu gew\u00e4hrleisten. <\/p>\n<p><b>4. Welche Art von Unterst\u00fctzung bietet Sobel f\u00fcr die Einhaltung des QMS?<\/b><\/p>\n<p>Sobel bietet drei erg\u00e4nzende Dienstleistungen an: Interne Audits, Gap-Analyse (RDC 665\/2022) und Gap-Analyse (ISO 13485:2016). Unsere Experten bewerten Ihr System, identifizieren Nichtkonformit\u00e4ten und liefern umsetzbare Anleitungen, damit Sie die vollst\u00e4ndige Konformit\u00e4t effizient erreichen. <\/p>\n<p><b>5. Hilft Sobel bei der Umsetzung von Korrekturma\u00dfnahmen oder neuen Verfahren?<\/b><\/p>\n<p>Unser Aufgabenbereich konzentriert sich auf die Bewertung und Beratung.<\/p>\n<p><b>6. Warum Sobel f\u00fcr die Unterst\u00fctzung des Qualit\u00e4tsmanagementsystems in Brasilien w\u00e4hlen?<\/b><\/p>\n<p>Sobel kombiniert fundierte Kenntnisse der regulatorischen Anforderungen von Anvisa mit internationalem Fachwissen \u00fcber Qualit\u00e4tsmanagementsysteme nach ISO 13485. Wir machen die Einhaltung der Vorschriften klarer, schneller und strategischer - und helfen Ihnen, sich auf Audits vorzubereiten, die Zertifizierung zu erlangen und die Qualit\u00e4t langfristig aufrechtzuerhalten. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Holen Sie sich fachkundige Unterst\u00fctzung f\u00fcr das Qualit\u00e4tsmanagement in Brasilien. Richten Sie Ihr QMS auf die Anforderungen von ISO 13485, RDC 665\/2022 und Anvisa f\u00fcr Medizinprodukte aus. <\/p>\n","protected":false},"author":16,"featured_media":7200,"parent":8431,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7904","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Qualit\u00e4tsmanagementsystem in Brasilien | Anvisa Compliance<\/title>\n<meta name=\"description\" content=\"Holen Sie sich fachkundige Unterst\u00fctzung, um Ihr Qualit\u00e4tsmanagementsystem in Brasilien an die Anforderungen von ISO 13485 und RDC 665\/2022 anzupassen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unterst\u00fctzung im Qualit\u00e4tsmanagement - Brasilien\" \/>\n<meta property=\"og:description\" content=\"Holen Sie sich fachkundige Unterst\u00fctzung, um Ihr Qualit\u00e4tsmanagementsystem in Brasilien an die Anforderungen von ISO 13485 und RDC 665\/2022 anzupassen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T19:33:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/04\/Quality-Management.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/\",\"name\":\"Qualit\u00e4tsmanagementsystem in Brasilien | Anvisa Compliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Quality-Management.webp\",\"datePublished\":\"2025-06-01T13:00:00+00:00\",\"dateModified\":\"2026-04-11T19:33:05+00:00\",\"description\":\"Holen Sie sich fachkundige Unterst\u00fctzung, um Ihr Qualit\u00e4tsmanagementsystem in Brasilien an die Anforderungen von ISO 13485 und RDC 665\\\/2022 anzupassen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Quality-Management.webp\",\"contentUrl\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Quality-Management.webp\",\"width\":1000,\"height\":657,\"caption\":\"Standard quality control collage concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/quality-management-system-brazil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsere L\u00f6sungen Brasilien\",\"item\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/our-solutions-brazil\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unterst\u00fctzung im Qualit\u00e4tsmanagement &#8211; Brasilien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/\",\"name\":\"Sobel\",\"description\":\"Regulatory Consultancy\",\"publisher\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/#organization\",\"name\":\"Sobel\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-Oficial-Website-White.png\",\"contentUrl\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-Oficial-Website-White.png\",\"width\":741,\"height\":290,\"caption\":\"Sobel\"},\"image\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qualit\u00e4tsmanagementsystem in Brasilien | Anvisa Compliance","description":"Holen Sie sich fachkundige Unterst\u00fctzung, um Ihr Qualit\u00e4tsmanagementsystem in Brasilien an die Anforderungen von ISO 13485 und RDC 665\/2022 anzupassen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/","og_locale":"de_DE","og_type":"article","og_title":"Unterst\u00fctzung im Qualit\u00e4tsmanagement - Brasilien","og_description":"Holen Sie sich fachkundige Unterst\u00fctzung, um Ihr Qualit\u00e4tsmanagementsystem in Brasilien an die Anforderungen von ISO 13485 und RDC 665\/2022 anzupassen.","og_url":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/","og_site_name":"Sobel","article_modified_time":"2026-04-11T19:33:05+00:00","og_image":[{"width":1000,"height":657,"url":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/04\/Quality-Management.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/","url":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/","name":"Qualit\u00e4tsmanagementsystem in Brasilien | Anvisa Compliance","isPartOf":{"@id":"https:\/\/sobelconsult.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/#primaryimage"},"image":{"@id":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/#primaryimage"},"thumbnailUrl":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/04\/Quality-Management.webp","datePublished":"2025-06-01T13:00:00+00:00","dateModified":"2026-04-11T19:33:05+00:00","description":"Holen Sie sich fachkundige Unterst\u00fctzung, um Ihr Qualit\u00e4tsmanagementsystem in Brasilien an die Anforderungen von ISO 13485 und RDC 665\/2022 anzupassen.","breadcrumb":{"@id":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/#primaryimage","url":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/04\/Quality-Management.webp","contentUrl":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/04\/Quality-Management.webp","width":1000,"height":657,"caption":"Standard quality control collage concept"},{"@type":"BreadcrumbList","@id":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/quality-management-system-brazil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sobelconsult.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Unsere L\u00f6sungen Brasilien","item":"https:\/\/sobelconsult.com\/de\/our-solutions-brazil\/"},{"@type":"ListItem","position":3,"name":"Unterst\u00fctzung im Qualit\u00e4tsmanagement &#8211; Brasilien"}]},{"@type":"WebSite","@id":"https:\/\/sobelconsult.com\/de\/#website","url":"https:\/\/sobelconsult.com\/de\/","name":"Sobel","description":"Regulatory Consultancy","publisher":{"@id":"https:\/\/sobelconsult.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sobelconsult.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sobelconsult.com\/de\/#organization","name":"Sobel","url":"https:\/\/sobelconsult.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sobelconsult.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2024\/07\/Logo-Oficial-Website-White.png","contentUrl":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2024\/07\/Logo-Oficial-Website-White.png","width":741,"height":290,"caption":"Sobel"},"image":{"@id":"https:\/\/sobelconsult.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/pages\/7904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/comments?post=7904"}],"version-history":[{"count":7,"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/pages\/7904\/revisions"}],"predecessor-version":[{"id":33979,"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/pages\/7904\/revisions\/33979"}],"up":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/pages\/8431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/media\/7200"}],"wp:attachment":[{"href":"https:\/\/sobelconsult.com\/de\/wp-json\/wp\/v2\/media?parent=7904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}