{"id":7514,"date":"2025-06-01T10:00:00","date_gmt":"2025-06-01T13:00:00","guid":{"rendered":"https:\/\/sobelconsult.com\/?page_id=7514"},"modified":"2026-02-12T09:23:40","modified_gmt":"2026-02-12T12:23:40","slug":"facility-registration-in-canada","status":"publish","type":"page","link":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/","title":{"rendered":"COS - CA - Registro de instala\u00e7\u00f5es"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7514\" class=\"elementor elementor-7514 elementor-6050\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-277edad e-flex e-con-boxed e-con e-parent\" data-id=\"277edad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9af4de elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f9af4de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d652181 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d652181\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Facility registration in Canada is a mandatory step for foreign cosmetic manufacturers and importers seeking to commercialize products in the country. With Sobel as your regulatory partner, your company stays compliant with Health Canada\u2019s Cosmetic Regulations and gains a faster, safer, and clearer path to market approval.\"}]\" data-inline-monday=\"true\">O cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1 \u00e9 uma etapa obrigat\u00f3ria para marcas estrangeiras que desejam comercializar produtos no pa\u00eds. Com a Sobel como parceira regulat\u00f3ria, sua empresa fica em conformidade com as regulamenta\u00e7\u00f5es de cosm\u00e9ticos da Health Canada e obt\u00e9m um caminho seguro e claro para a aprova\u00e7\u00e3o do mercado. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d58773f elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"d58773f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0NSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tenha suporte especializado<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4d020a e-flex e-con-boxed e-con e-parent\" data-id=\"f4d020a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd1c7d7 e-con-full e-flex e-con e-child\" data-id=\"dd1c7d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c25291d e-con-full e-transform e-flex e-con e-child\" data-id=\"c25291d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:96,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-109,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c63277b elementor-widget elementor-widget-heading\" data-id=\"c63277b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Para quem?<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e30c7fc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e30c7fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d5d2cf elementor-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5d5d2cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fabricantes estrangeiros de cosm\u00e9ticos que querem entrar no mercado canadense;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Empresas internacionais que precisam atualizar ou manter cadastros existentes;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Importadores respons\u00e1veis pela conformidade com os regulamentos da Health Canada.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-889dc46 e-con-full e-flex e-con e-child\" data-id=\"889dc46\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-780e535 elementor-widget elementor-widget-image\" data-id=\"780e535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"755\" height=\"1024\" src=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/section-fundo-755x1024.png\" class=\"attachment-large size-large wp-image-13865\" alt=\"Cosmetic products in amber bottles. Regulatory Affairs Cosmetics.\" srcset=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/section-fundo-755x1024.png 755w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/section-fundo-221x300.png 221w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/section-fundo-768x1041.png 768w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/section-fundo.png 1011w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c19a03 e-flex e-con-boxed e-con e-parent\" data-id=\"9c19a03\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1daaba elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b1daaba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"With Sobel, you gain a trusted partner to guide you through every step of facility registration in Canada.\"}]\" data-inline-monday=\"true\">Com a Sobel, voc\u00ea ganha um parceiro confi\u00e1vel para orient\u00e1-lo em todas as etapas do cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84b6555 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"84b6555\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0NSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenha suporte!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eabb1a5 e-flex e-con-boxed e-con e-parent\" data-id=\"eabb1a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae93080 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"ae93080\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1803\" height=\"278\" src=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/sec-cosmetics.png\" class=\"attachment-full size-full wp-image-13877\" alt=\"Shape pink\" srcset=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/sec-cosmetics.png 1803w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/sec-cosmetics-300x46.png 300w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/sec-cosmetics-1024x158.png 1024w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/sec-cosmetics-768x118.png 768w, https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/sec-cosmetics-1536x237.png 1536w\" sizes=\"(max-width: 1803px) 100vw, 1803px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b70821e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b70821e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Por que voc\u00ea precisa desse servi\u00e7o?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62cd14f e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"62cd14f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-08aae7b e-con-full e-flex e-con e-child\" data-id=\"08aae7b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fea0c4 elementor-widget elementor-widget-text-editor\" data-id=\"4fea0c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Registering your cosmetic facility with Health Canada is mandatory, and missing requirements can block your products from the Canadian market.\"}]\" data-inline-monday=\"true\">O cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1 \u00e9 obrigat\u00f3rio, algo que pode impedir que seus produtos entrem no mercado canadense.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dad3eb3 e-con-full e-flex e-con e-child\" data-id=\"dad3eb3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27b20f6 elementor-widget elementor-widget-text-editor\" data-id=\"27b20f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"We help your company speed up market entry by managing filings and follow-ups directly with Health Canada.\"}]\" data-inline-monday=\"true\">Com suporte especializado, sua empresa pode acelerar a entrada no mercado, gerenciando os registros diretamente com a Health Canada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79bca30 e-con-full e-flex e-con e-child\" data-id=\"79bca30\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccd1512 elementor-widget elementor-widget-text-editor\" data-id=\"ccd1512\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Our team provides Canadian address compliance and support as regulations evolve.\"}]\" data-inline-monday=\"true\">Nossa equipe oferece conformidade com os endere\u00e7os canadenses e suporte \u00e0 medida que as regulamenta\u00e7\u00f5es evoluem.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ec2638 e-flex e-con-boxed e-con e-parent\" data-id=\"1ec2638\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8f1b330 e-con-full e-flex e-con e-child\" data-id=\"8f1b330\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-086fa73 elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"086fa73\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Suporte passo a passo para o cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdd56a9 e-con-full e-flex e-con e-child\" data-id=\"cdd56a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa6d127 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fa6d127\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O registro da sua instala\u00e7\u00e3o de cosm\u00e9ticos no Health Canada n\u00e3o \u00e9 opcional: \u00e9 uma exig\u00eancia legal.<\/p><p>A Sobel ajuda a orientar o seu cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1 para que ele seja preciso, esteja em conformidade e alinhado com as regulamenta\u00e7\u00f5es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de7f2d5 e-flex e-con-boxed e-con e-parent\" data-id=\"de7f2d5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4cafb0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d4cafb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Um caminho claro para o cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3bebb9 elementor-widget elementor-widget-ucaddon_horizontal_timeline\" data-id=\"c3bebb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_horizontal_timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Horizontal Timeline -->\n\t\t<link id='font-awesome-css' href='https:\/\/sobelconsult.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/sobelconsult.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/sobelconsult.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Horizontal Timeline *\/\n\n#uc_horizontal_timeline_elementor_c3bebb9 *{\n  box-sizing:border-box;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9{\n  position:relative;\n  min-height:1px;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-carousel-content{\n    display: flex;\n    flex-flow: column nowrap;\n    flex:1;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-carousel-item{\n  overflow:hidden;\n  position:relative;\n  display:flex;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-btn-holder{\n  margin-top:auto;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-btn{\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n} \n\n#uc_horizontal_timeline_elementor_c3bebb9 .item-horizontal-timeline .ue-item-title{\n  font-size:21px;\n  text-decoration:none;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .carousel-nav{\n  position:relative;\n  z-index:10;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .carousel-nav .carousel-prev{\n    position:absolute;\n      display:inline-block;    \n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .carousel-nav .carousel-next{\n  position:absolute;\n  display:inline-block;    \n}\n\n#uc_horizontal_timeline_elementor_c3bebb9  .carousel-nav button svg, \n#uc_horizontal_timeline_elementor_c3bebb9  .carousel-nav button i{\n  position: absolute;\n     top: 50%;\n  left: 50%;\n  transform: translate(-50%, -50%);\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .owl-dots {\n  overflow:hidden;\n  display:true !important;  \n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .owl-dot {\n  border-radius:50%;\n  display:inline-block;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-bullet-holder{\n  display:flex;\n  align-items:center;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-bullet-line{\n  flex-grow:1;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-bullet-line-spacing{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-bullet{\n  position:relative;\n  transition: all .3s ease;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-bullet i, #uc_horizontal_timeline_elementor_c3bebb9 .ue-item-bullet svg{\n  position: absolute;\n  top: 50%;\n  left: 50%;\n  transform: translate(-50%, -50%); \n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-label a{\n  font-size:12px;\n  line-height:1.5em;\n  text-decoration:none;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-image{\n  overflow:hidden;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-image a{\n  display:block;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-image img{\n  object-fit: cover;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-vertical-line-holder{\n  display:flex;\n  justify-content:center; \n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-pointer-holder{\n  display:flex;\n  justify-content:center; \n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-carousel-item:hover .ue-item-image img{\n  transform:scale(1.1,1.1);\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-item-label{\n display:inline-block;\n}\n\n#uc_horizontal_timeline_elementor_c3bebb9 .ue-carousel-item-holder{\n  display: flex;\n  flex-direction: column;\n  align-items: stretch;\n  height:100%;\n}\n\n<\/style>\n\n<div class=\"ue-horizontal-timeline\" id=\"uc_horizontal_timeline_elementor_c3bebb9\">\n     <div class=\"carousel-nav\">\n            <button class=\"carousel-prev\" aria-label=\"Previous\">\n                <i class=' ti-arrow-circle-left'><\/i>\n            <\/button>\n            <button class=\"carousel-next\" aria-label=\"Next\">\n                <i class=' ti-arrow-circle-right'><\/i>\n            <\/button>\n        <\/div>\n    <div class=\"owl-carousel owl-theme uc-items-wrapper item-horizontal-timeline  \" id=\"uc_horizontal_timeline_elementor_c3bebb9\" data-custom-sethtml=\"true\"  >\n     \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-e7927f1\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >In\u00edcio da parceria<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">A Sobel atua como seu parceiro regulat\u00f3rio, coordenando todas as etapas para o cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-4a90fc4\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >Alinhamento regulat\u00f3rio<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">Analisamos a documenta\u00e7\u00e3o de suas instala\u00e7\u00f5es para confirmar a conformidade com as expectativas da Health Canada para fabricantes estrangeiros.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-658ffc1\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >Prepara\u00e7\u00e3o e envio de documentos<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">Preparamos documentos e apoiamos o seu envio \u00e0 Health Canada.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n \n\n\n<div class=\"ue-carousel-item elementor-repeater-item-41d4751\">\n    <div class=\"ue-item-bullet-holder\">\n    <div class=\"ue-item-bullet-line\"><\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet\">\n      <i class='lnr lnr-checkmark-circle'><\/i>          <\/div>\n    <div class=\"ue-item-bullet-line-spacing\"><\/div>\n    <div class=\"ue-item-bullet-line\"><\/div>\n  <\/div>\n\n   \n\n    <div class=\"ue-item-vertical-line-holder\">\n    <div class=\"ue-item-vertical-line\"><\/div>\n  <\/div>\n    \n    <div class=\"ue-item-pointer-holder\">\n    <div class=\"ue-item-pointer\"><\/div>\n  <\/div>\n    \n   <div class=\"ue-carousel-item-holder\">\n    \n          <div class=\"ue-carousel-content\">\n        <div class=\"ue-carousel-content-inside\">\n                    <div class=\"ue-item-title\">\n            <a href=\"#\" >Suporte regulat\u00f3rio<\/a>\n          <\/div>\n                    <div class=\"ue-item-intro\">A Sobel continua dispon\u00edvel para ajudar voc\u00ea com as altera\u00e7\u00f5es e com as solicita\u00e7\u00f5es da Health Canada.<\/div>\n                    <\/div>\n\n              <\/div>\n      <\/div>\n<\/div>\n\n  <\/div>\n<\/div>\n<!-- end Horizontal Timeline -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d33f0d8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d33f0d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0NSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comece agora!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7908cb e-flex e-con-boxed e-con e-parent\" data-id=\"c7908cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-08dcc13 e-con-full e-flex e-con e-child\" data-id=\"08dcc13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cf57de elementor-widget__width-inherit elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"3cf57de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8015d9 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f8015d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servi\u00e7os relacionados <br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c1e0bd elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2c1e0bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"{\"alignment\":\"left\",\"direction\":\"ltr\",\"deltaFormat\":[{\"insert\":\"Sobel makes the Canadian regulatory pathway clear and straightforward, helping you avoid errors and wasted time.\"}],\"base64Encoded\":\"BQGIrrP0DwABAQl0ZXh0QmxvY2tkAfDk24YOAIGL1KKuArEBbwGL1KKuAgCB15SkBBCyAQHNibCrAQCE8OTbhg5ucFNvYmVsIG1ha2VzIHRoZSBDYW5hZGlhbiByZWd1bGF0b3J5IHBhdGh3YXkgY2xlYXIgYW5kIHN0cmFpZ2h0Zm9yd2FyZCwgaGVscGluZyB5b3UgYXZvaWQgZXJyb3JzIGFuZCB3YXN0ZWQgdGltZS4B15SkBACBiK6z9A9jEQSIrrP0DwEAZNeUpAQBABGL1KKuAgEAsgHw5NuGDgEAbw==\"}\" data-monday-block-id=\"332de8f6-1745-428b-8b86-598f9363a41b\" data-monday-block-collapsed=\"undefined\" data-monday-block-is-collapsed-header=\"false\" data-monday-block-doc-id=\"29773374\"> <\/p><p>A Sobel torna o caminho regulat\u00f3rio canadense claro e direto, ajudando voc\u00ea a evitar erros e perda de tempo.<\/p><p>Voc\u00ea pode ampliar sua jornada de conformidade com nossos servi\u00e7os regulat\u00f3rios adicionais:<\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7041cc e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b7041cc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5dd19d8 e-con-full e-flex e-con e-child\" data-id=\"5dd19d8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3434edb elementor-widget elementor-widget-heading\" data-id=\"3434edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Classifica\u00e7\u00e3o do Produto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7222743 elementor-widget elementor-widget-text-editor\" data-id=\"7222743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Assessment to classify your product as a cosmetic, natural health product, or other.\"}]\" data-inline-monday=\"true\">Aux\u00edlio para classificar o produto como cosm\u00e9tico, cosm\u00e9tico natural ou outros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-415e3a0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"415e3a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/classificacao-de-produtos-cosmeticos-no-canada\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81fe456 e-con-full e-flex e-con e-child\" data-id=\"81fe456\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5712032 elementor-widget elementor-widget-heading\" data-id=\"5712032\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pacote de registro de cosm\u00e9ticos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f169e elementor-widget elementor-widget-text-editor\" data-id=\"25f169e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d42130 elementor-widget elementor-widget-text-editor\" data-id=\"7d42130\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-element elementor-element-7d42130 elementor-widget elementor-widget-text-editor\" data-id=\"7d42130\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Regulatory consulting for cosmetic notification and compliance to Health Canada. \"}]\" data-inline-monday=\"true\">Pacote de consultoria regulat\u00f3ria para notifica\u00e7\u00e3o de cosm\u00e9ticos \u00e0 Health Canada. <\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78a7ca1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"78a7ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/pacote-notificacao-de-cosmeticos-no-canada\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1128789 e-con-full e-flex e-con e-child\" data-id=\"1128789\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-055336d elementor-widget elementor-widget-heading\" data-id=\"055336d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suporte \u00e0 Vigil\u00e2ncia P\u00f3s-Mercado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55c4388 elementor-widget elementor-widget-text-editor\" data-id=\"55c4388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"monday-block-1\" contenteditable=\"true\" data-monday-block-type=\"1\" data-monday-block-content=\"[{\"insert\":\"Support in handling adverse reactions and Health Canada compliance issues.\"}]\" data-inline-monday=\"true\">Apoio no gerenciamento de rea\u00e7\u00f5es adversas e quest\u00f5es de conformidade.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a44ac7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6a44ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/post-market-surveillance-canada\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1eda669 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1eda669\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8a49380 e-con-full e-flex e-con e-child\" data-id=\"8a49380\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-febcc0d e-con-full e-flex e-con e-child\" data-id=\"febcc0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20174aa elementor-widget elementor-widget-heading\" data-id=\"20174aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obtenha suporte especializado para o cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22dd87 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e22dd87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Sobel oferece suporte a fabricantes e importadores estrangeiros de cosm\u00e9ticos com o registro de instala\u00e7\u00f5es para obter total conformidade com os requisitos da Health Canada.<\/p><p><strong>Tenha nossa equipe ao seu lado para tornar o processo mais r\u00e1pido, claro e direto!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abd880d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"abd880d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NzM0NSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tenha suporte especializado<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0128781 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"0128781\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b897d elementor-widget__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"f0b897d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Voc\u00ea ainda tem d\u00favidas? D\u00ea uma olhada em nosso FAQ. <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2521\"><p><strong>1. O cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1 \u00e9 obrigat\u00f3rio?<\/strong><\/p>\n<p>Sim. A Health Canada exige que todos os fabricantes e importadores estrangeiros de cosm\u00e9ticos notifiquem seus produtos por meio do Formul\u00e1rio de Notifica\u00e7\u00e3o de Cosm\u00e9ticos (CNF). Desde mar\u00e7o de 2025, um endere\u00e7o canadense tamb\u00e9m \u00e9 exigido em cada CNF.  <\/p>\n<p><strong>2. Quem \u00e9 respons\u00e1vel por enviar o Formul\u00e1rio de Notifica\u00e7\u00e3o de Cosm\u00e9ticos?<\/strong><\/p>\n<p>A responsabilidade legal pelo envio do CNF \u00e9 do fabricante ou importador listado no formul\u00e1rio. No entanto, a Sobel gerencia todo o processo em seu nome: coletamos as informa\u00e7\u00f5es necess\u00e1rias, preparamos a documenta\u00e7\u00e3o e coordenamos o arquivamento passo a passo. Dessa forma, voc\u00ea evita erros, atrasos e rejei\u00e7\u00f5es da Health Canada.  <\/p>\n<p><strong>3. Preciso de um endere\u00e7o canadense para concluir o registro da instala\u00e7\u00e3o no Canad\u00e1?<\/strong><\/p>\n<p>Sim. Desde mar\u00e7o de 2025, a Health Canada exige que cada CNF inclua um endere\u00e7o canadense v\u00e1lido. Sem ele, sua notifica\u00e7\u00e3o n\u00e3o ser\u00e1 aceita.  <\/p>\n<p><strong>4. O cadastro de fabricante de cosm\u00e9ticos no Canad\u00e1 inclui inspe\u00e7\u00f5es de f\u00e1brica?<\/strong><\/p>\n<p>N\u00e3o. A Health Canada n\u00e3o realiza inspe\u00e7\u00f5es de rotina em f\u00e1bricas de cosm\u00e9ticos, mas espera a conformidade com as Boas Pr\u00e1ticas de Fabrica\u00e7\u00e3o (BPFs) e pode agir em caso de preocupa\u00e7\u00f5es com a seguran\u00e7a. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.<\/p>\n","protected":false},"author":16,"featured_media":13836,"parent":16227,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7514","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cadastro de Fabricante de Cosm\u00e9ticos no Canad\u00e1<\/title>\n<meta name=\"description\" content=\"Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COS - CA - Registro de instala\u00e7\u00f5es\" \/>\n<meta property=\"og:description\" content=\"Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T12:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/hero-sec-ca-comsetics-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/\",\"name\":\"Cadastro de Fabricante de Cosm\u00e9ticos no Canad\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/hero-sec-ca-comsetics-3.png\",\"datePublished\":\"2025-06-01T13:00:00+00:00\",\"dateModified\":\"2026-02-12T12:23:40+00:00\",\"description\":\"Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/hero-sec-ca-comsetics-3.png\",\"contentUrl\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/hero-sec-ca-comsetics-3.png\",\"width\":2200,\"height\":1236,\"caption\":\"Cosmetic products Canada. Canada Regulatory Affairs.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/facility-registration-in-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nossas solu\u00e7\u00f5es Cosmetics Canada\",\"item\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/registro-de-cosmeticos-no-canada\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COS &#8211; CA &#8211; Registro de instala\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/\",\"name\":\"Sobel\",\"description\":\"Regulatory Consultancy\",\"publisher\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/#organization\",\"name\":\"Sobel\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-Oficial-Website-White.png\",\"contentUrl\":\"https:\\\/\\\/sobelconsult.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-Oficial-Website-White.png\",\"width\":741,\"height\":290,\"caption\":\"Sobel\"},\"image\":{\"@id\":\"https:\\\/\\\/sobelconsult.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cadastro de Fabricante de Cosm\u00e9ticos no Canad\u00e1","description":"Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/","og_locale":"pt_BR","og_type":"article","og_title":"COS - CA - Registro de instala\u00e7\u00f5es","og_description":"Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.","og_url":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/","og_site_name":"Sobel","article_modified_time":"2026-02-12T12:23:40+00:00","og_image":[{"width":2200,"height":1236,"url":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/hero-sec-ca-comsetics-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/","url":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/","name":"Cadastro de Fabricante de Cosm\u00e9ticos no Canad\u00e1","isPartOf":{"@id":"https:\/\/sobelconsult.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/#primaryimage"},"image":{"@id":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/hero-sec-ca-comsetics-3.png","datePublished":"2025-06-01T13:00:00+00:00","dateModified":"2026-02-12T12:23:40+00:00","description":"Orientamos os fabricantes de cosm\u00e9ticos estrangeiros a cumprir os regulamentos da Health Canada, incluindo o cadastro no Canad\u00e1.","breadcrumb":{"@id":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/#primaryimage","url":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/hero-sec-ca-comsetics-3.png","contentUrl":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2025\/09\/hero-sec-ca-comsetics-3.png","width":2200,"height":1236,"caption":"Cosmetic products Canada. Canada Regulatory Affairs."},{"@type":"BreadcrumbList","@id":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/facility-registration-in-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sobelconsult.com\/pt-br\/home\/"},{"@type":"ListItem","position":2,"name":"Nossas solu\u00e7\u00f5es Cosmetics Canada","item":"https:\/\/sobelconsult.com\/pt-br\/registro-de-cosmeticos-no-canada\/"},{"@type":"ListItem","position":3,"name":"COS &#8211; CA &#8211; Registro de instala\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/sobelconsult.com\/pt-br\/#website","url":"https:\/\/sobelconsult.com\/pt-br\/","name":"Sobel","description":"Regulatory Consultancy","publisher":{"@id":"https:\/\/sobelconsult.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sobelconsult.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sobelconsult.com\/pt-br\/#organization","name":"Sobel","url":"https:\/\/sobelconsult.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sobelconsult.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2024\/07\/Logo-Oficial-Website-White.png","contentUrl":"https:\/\/sobelconsult.com\/wp-content\/uploads\/2024\/07\/Logo-Oficial-Website-White.png","width":741,"height":290,"caption":"Sobel"},"image":{"@id":"https:\/\/sobelconsult.com\/pt-br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/pages\/7514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/comments?post=7514"}],"version-history":[{"count":5,"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/pages\/7514\/revisions"}],"predecessor-version":[{"id":30945,"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/pages\/7514\/revisions\/30945"}],"up":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/pages\/16227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/media\/13836"}],"wp:attachment":[{"href":"https:\/\/sobelconsult.com\/pt-br\/wp-json\/wp\/v2\/media?parent=7514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}